{"id":4835,"date":"2023-10-20T18:15:06","date_gmt":"2023-10-20T16:15:06","guid":{"rendered":"https:\/\/bekeffyfootball.com\/?p=4835"},"modified":"2023-10-20T18:20:07","modified_gmt":"2023-10-20T16:20:07","slug":"adamo-coulibaly-3","status":"publish","type":"post","link":"https:\/\/bekeffyfootball.com\/fr\/hirek\/adamo-coulibaly-3\/","title":{"rendered":"Adamo Coulibaly"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4835\" class=\"elementor elementor-4835\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bf73e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bf73e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e396fa4\" data-id=\"1e396fa4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e3682 elementor-widget elementor-widget-image\" data-id=\"69e3682\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"370\" height=\"244\" src=\"https:\/\/bekeffyfootball.com\/wp-content\/uploads\/2023\/09\/main_culibali2.jpg\" class=\"attachment-full size-full wp-image-2003\" alt=\"\" srcset=\"https:\/\/bekeffyfootball.com\/wp-content\/uploads\/2023\/09\/main_culibali2.jpg 370w, https:\/\/bekeffyfootball.com\/wp-content\/uploads\/2023\/09\/main_culibali2-300x198.jpg 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47a203da elementor-widget elementor-widget-text-editor\" data-id=\"47a203da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Entretien \u00e1 Budapest avec notre nouveau joueur, Adamo Coulibaly<\/strong><\/p><p><strong>Adamo Coulibaly<\/strong> est un footballeur francais d&rsquo;origine ivoirienne, n\u00e9 le 14 aout 1981 \u00e0 Noisy-le-Grand.<\/p><p>Les d\u00e9buts professionnels (en Belgique \u00e0 Saint-Trond puis Anvers)<br \/>Malgr\u00e9 ses 7 buts et 7 passes d\u00e9cisives, le club de Saint-Trond VV est rel\u00e9gu\u00e9 de Division 1, il signe alors au Royal Antwerp FC en Division 2 le 1er juillet 2008. Apr\u00e8s une saison moyenne, o\u00f9 il joue peu \u00e0 son poste de pr\u00e9dilection, attaquant de pointe, Debrecen VSC, qui l&rsquo;avait d\u00e9j\u00e0 sollicit\u00e9, revient \u00e0 la charge et il signe au club, sans que celui-ci n&rsquo;ait \u00e0 verser d&rsquo;indemnit\u00e9s de transferts, trois jours avant le d\u00e9but des tours pr\u00e9liminaires de la Ligue des Champions le 15 juillet 2009.<\/p><p>R\u00e9v\u00e9lation chez les pros puis Ligue des Champions (en Hongrie \u00e0 Debrecen)<br \/>Au second tour des qualifications de la Ligue des Champions, il est d\u00e9cisif contre les Estoniens du FC Levadia Tallinn avec une passe d\u00e9cisive \u00e0 l&rsquo;aller et un but au retour.<\/p><p>Tout comme son club, il participe pour la premi\u00e8re fois \u00e0 la prestigieuse phase finale de la Ligue des Champions. Il joue les matchs contre Liverpool FC le 16 septembre 2009 et contre l&rsquo;Olympique Lyonnais le 29 septembre 2009.<\/p><p>Il inscrit un but contre la Fiorentina le 20 octobre 2009 \u00e0 la 88e minute, mais il n&#8217;empoche pas la prime de 1 million de forints (environ 3700 euros) promis au premier buteur du club en phase de groupe.<\/p><p>Il indique alors : \u00ab \u00c7a me ferait plaisir de jouer en France, ce serait le fruit de tous mes efforts, conclut-il. Si \u00e7a se passe bien, je serai expos\u00e9. La Ligue des Champions, c&rsquo;est une vitrine pour les joueurs, il ne faut pas se mentir. Finir dans un grand club, \u00e7a serait une belle histoire, non ?<\/p><p>Il inscrit de nouveau un but contre la Fiorentina le 4 novembre 2009 \u00e0 la 70e minute alors qu&rsquo;il \u00e9tait entr\u00e9 en jeu \u00e0 la 53e minute en remplacement de Luis Ramos, mais il n&#8217;emp\u00eache pas la d\u00e9faite de son \u00e9quipe 5 \u00e0 2 lors de la 4e journ\u00e9e du groupe E.<\/p><p>Le 1 mai 2012il remporte la Coupe de Hongrie avec Debrecen VSC en battant le MTK Budapest FC. C&rsquo;est la cinqui\u00e8me Coupe de Hongrie pour Debrecen VSC8.<\/p><p>Le 12 mai 2012 il remporte la ligue hongroise avec son club, apr\u00e8s avoir battu P\u00e9cs lors de la 28\u00e8me journ\u00e9e par 4-0 au Stadium Ol\u00e1h G\u00e1bor \u00fat, le sixi\u00e8me titre pour le club9.<\/p><p>Le 26 mai 2012 il marque un penalty contre Szombathely, ce qui porte son total de but \u00e0 20 pour la saison. Il a d\u00e9pass\u00e9 Nemanja Nikolic dans le classement des buteurs et est devenu le meilleur buteur de la saison 2011-12 de la Ligue hongroise. Son sang froid devant le but et la consistance de son jeu lui valent rapidement le surnom de \u00ab\u00a0Guly\u00e1sleves\u00a0\u00bb,en r\u00e9f\u00e9rence au plat national hongrois (le goulash).<\/p><p>La recherche de reconnaissance (en France \u00e0 Lens)<br \/>Lors de l&rsquo;\u00e9t\u00e9 2013, il passe un essai au RC Lens et y signe pour un bail de deux ans.<\/p><p>Il inscrit son premier but avec les Lensois sur p\u00e9nalty face \u00e0 l&rsquo; US Cr\u00e9teil en Coupe de la Ligue le 27 aout 2013 . Puis il marque son premier but en championnat lors de la 5\u00e8me journ\u00e9e face \u00e0 l&rsquo;ES Troyes AC, match remport\u00e9 1 \u00e0 0.<\/p><p>Le 16 mai 2014, lors de la derni\u00e8re journ\u00e9e, Adamo Coulibaly inscrit un doubl\u00e9 contre le CA Bastia et permet au RC Lens de l&#8217;emporter 2-0 et d&rsquo;obtenir la mont\u00e9e en Ligue 1<\/p><p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Entretien \u00e1 Budapest avec notre nouveau joueur, Adamo Coulibaly Adamo Coulibaly est un footballeur francais d&rsquo;origine ivoirienne, n\u00e9 le 14 aout 1981 \u00e0 Noisy-le-Grand. Les d\u00e9buts professionnels (en Belgique \u00e0 Saint-Trond puis Anvers)Malgr\u00e9 ses 7 buts et 7 passes d\u00e9cisives, le club de Saint-Trond VV est rel\u00e9gu\u00e9 de Division 1, il signe alors au Royal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[100],"tags":[],"class_list":["post-4835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hirek","entry","has-media"],"_links":{"self":[{"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/posts\/4835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/comments?post=4835"}],"version-history":[{"count":0,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/posts\/4835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/media\/2003"}],"wp:attachment":[{"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/media?parent=4835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/categories?post=4835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bekeffyfootball.com\/fr\/wp-json\/wp\/v2\/tags?post=4835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}